{"id":679,"date":"2017-07-07T13:19:40","date_gmt":"2017-07-07T11:19:40","guid":{"rendered":"http:\/\/wcdra.shopworks-clients.nl\/?p=679"},"modified":"2019-11-12T13:25:57","modified_gmt":"2019-11-12T13:25:57","slug":"dra-yemen-gezamenlijke-reactie","status":"publish","type":"post","link":"https:\/\/dutchrelief.org\/nl\/dra-yemen-joint-response\/","title":{"rendered":"Bekijk onze projecten in Jemen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":698,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Witness Our Projects in Yemen | Dutch Relief Alliance<\/title>\n<meta name=\"description\" content=\"Our new video highlights the work of the Dutch Relief Alliance to assist IDPs affected by the Yemen conflict.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dutchrelief.org\/nl\/dra-yemen-gezamenlijke-reactie\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Witness Our Projects in Yemen | Dutch Relief Alliance\" \/>\n<meta property=\"og:description\" content=\"Our new video highlights the work of the Dutch Relief Alliance to assist IDPs affected by the Yemen conflict.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dutchrelief.org\/nl\/dra-yemen-gezamenlijke-reactie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Relief Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-07T11:19:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-12T13:25:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dutchrelief.org\/wp-content\/uploads\/2017\/07\/yemenjulyweb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"platformpro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"platformpro\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/\"},\"author\":{\"name\":\"platformpro\",\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/#\\\/schema\\\/person\\\/1709201ed45787ca190899fcc0afb7dc\"},\"headline\":\"Witness Our Projects in Yemen\",\"datePublished\":\"2017-07-07T11:19:40+00:00\",\"dateModified\":\"2019-11-12T13:25:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dutchrelief.org\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/yemenjulyweb.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/\",\"url\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/\",\"name\":\"Witness Our Projects in Yemen | Dutch Relief Alliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dutchrelief.org\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/yemenjulyweb.jpg\",\"datePublished\":\"2017-07-07T11:19:40+00:00\",\"dateModified\":\"2019-11-12T13:25:57+00:00\",\"description\":\"Our new video highlights the work of the Dutch Relief Alliance to assist IDPs affected by the Yemen conflict.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dutchrelief.org\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/yemenjulyweb.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchrelief.org\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/yemenjulyweb.jpg\",\"width\":1200,\"height\":800,\"caption\":\"A young girl with wet hair looks directly at the camera while sitting next to a tree, her hand resting on the trunk. She wears a red sweater and a scarf around her head, with a somber expression, highlighting the vulnerability of children affected by crisis situations.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/dra-yemen-joint-response\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dutchrelief.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Witness Our Projects in Yemen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/#website\",\"url\":\"https:\\\/\\\/dutchrelief.org\\\/\",\"name\":\"Dutch Relief Alliance\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dutchrelief.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/#organization\",\"name\":\"Dutch Relief Alliance\",\"url\":\"https:\\\/\\\/dutchrelief.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dutchrelief.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-dra.png\",\"contentUrl\":\"https:\\\/\\\/dutchrelief.org\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-dra.png\",\"width\":1128,\"height\":338,\"caption\":\"Dutch Relief Alliance\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dutchrelief.org\\\/#\\\/schema\\\/person\\\/1709201ed45787ca190899fcc0afb7dc\",\"name\":\"platformpro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f33a190aaafff4b55ecd6762679d9e9576423835f7e246f58b05ce27733b7f30?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f33a190aaafff4b55ecd6762679d9e9576423835f7e246f58b05ce27733b7f30?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f33a190aaafff4b55ecd6762679d9e9576423835f7e246f58b05ce27733b7f30?s=96&d=mm&r=g\",\"caption\":\"platformpro\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bekijk onze projecten in Jemen | Dutch Relief Alliance","description":"Onze nieuwe video belicht het werk van het Dutch Relief Alliance om ontheemden te helpen die zijn getroffen door het conflict in Jemen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dutchrelief.org\/nl\/dra-yemen-gezamenlijke-reactie\/","og_locale":"nl_NL","og_type":"article","og_title":"Witness Our Projects in Yemen | Dutch Relief Alliance","og_description":"Our new video highlights the work of the Dutch Relief Alliance to assist IDPs affected by the Yemen conflict.","og_url":"https:\/\/dutchrelief.org\/nl\/dra-yemen-gezamenlijke-reactie\/","og_site_name":"Dutch Relief Alliance","article_published_time":"2017-07-07T11:19:40+00:00","article_modified_time":"2019-11-12T13:25:57+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/dutchrelief.org\/wp-content\/uploads\/2017\/07\/yemenjulyweb.jpg","type":"image\/jpeg"}],"author":"platformpro","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"platformpro"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/#article","isPartOf":{"@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/"},"author":{"name":"platformpro","@id":"https:\/\/dutchrelief.org\/#\/schema\/person\/1709201ed45787ca190899fcc0afb7dc"},"headline":"Witness Our Projects in Yemen","datePublished":"2017-07-07T11:19:40+00:00","dateModified":"2019-11-12T13:25:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/"},"wordCount":5,"publisher":{"@id":"https:\/\/dutchrelief.org\/#organization"},"image":{"@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchrelief.org\/wp-content\/uploads\/2017\/07\/yemenjulyweb.jpg","articleSection":["News"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/","url":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/","name":"Bekijk onze projecten in Jemen | Dutch Relief Alliance","isPartOf":{"@id":"https:\/\/dutchrelief.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/#primaryimage"},"image":{"@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchrelief.org\/wp-content\/uploads\/2017\/07\/yemenjulyweb.jpg","datePublished":"2017-07-07T11:19:40+00:00","dateModified":"2019-11-12T13:25:57+00:00","description":"Onze nieuwe video belicht het werk van het Dutch Relief Alliance om ontheemden te helpen die zijn getroffen door het conflict in Jemen.","breadcrumb":{"@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dutchrelief.org\/dra-yemen-joint-response\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/#primaryimage","url":"https:\/\/dutchrelief.org\/wp-content\/uploads\/2017\/07\/yemenjulyweb.jpg","contentUrl":"https:\/\/dutchrelief.org\/wp-content\/uploads\/2017\/07\/yemenjulyweb.jpg","width":1200,"height":800,"caption":"A young girl with wet hair looks directly at the camera while sitting next to a tree, her hand resting on the trunk. She wears a red sweater and a scarf around her head, with a somber expression, highlighting the vulnerability of children affected by crisis situations."},{"@type":"BreadcrumbList","@id":"https:\/\/dutchrelief.org\/dra-yemen-joint-response\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dutchrelief.org\/"},{"@type":"ListItem","position":2,"name":"Witness Our Projects in Yemen"}]},{"@type":"WebSite","@id":"https:\/\/dutchrelief.org\/#website","url":"https:\/\/dutchrelief.org\/","name":"Dutch Relief Alliance","description":"","publisher":{"@id":"https:\/\/dutchrelief.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dutchrelief.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/dutchrelief.org\/#organization","name":"Dutch Relief Alliance","url":"https:\/\/dutchrelief.org\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/dutchrelief.org\/#\/schema\/logo\/image\/","url":"https:\/\/dutchrelief.org\/wp-content\/uploads\/2019\/11\/logo-dra.png","contentUrl":"https:\/\/dutchrelief.org\/wp-content\/uploads\/2019\/11\/logo-dra.png","width":1128,"height":338,"caption":"Dutch Relief Alliance"},"image":{"@id":"https:\/\/dutchrelief.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dutchrelief.org\/#\/schema\/person\/1709201ed45787ca190899fcc0afb7dc","name":"platformpro","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/f33a190aaafff4b55ecd6762679d9e9576423835f7e246f58b05ce27733b7f30?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f33a190aaafff4b55ecd6762679d9e9576423835f7e246f58b05ce27733b7f30?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f33a190aaafff4b55ecd6762679d9e9576423835f7e246f58b05ce27733b7f30?s=96&d=mm&r=g","caption":"platformpro"}}]}},"_links":{"self":[{"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/posts\/679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/comments?post=679"}],"version-history":[{"count":0,"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/posts\/679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/media\/698"}],"wp:attachment":[{"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/media?parent=679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/categories?post=679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dutchrelief.org\/nl\/wp-json\/wp\/v2\/tags?post=679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}